{"id":2,"count":6,"description":"","link":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/","name":"Event Recap","slug":"event-recap","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Event Recap Archives - Powerfront Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Event Recap Archives - Powerfront Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/\" \/>\n<meta property=\"og:site_name\" content=\"Powerfront Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.powerfront.com\/blog\/#website\",\"url\":\"https:\/\/www.powerfront.com\/blog\/\",\"name\":\"Powerfront Blog\",\"description\":\"News, Insights, and Stories from Powerfront\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.powerfront.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#webpage\",\"url\":\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/\",\"name\":\"Event Recap Archives - Powerfront Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.powerfront.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.powerfront.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Event Recap\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Event Recap Archives - Powerfront Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/","og_locale":"en_US","og_type":"article","og_title":"Event Recap Archives - Powerfront Blog","og_url":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/","og_site_name":"Powerfront Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.powerfront.com\/blog\/#website","url":"https:\/\/www.powerfront.com\/blog\/","name":"Powerfront Blog","description":"News, Insights, and Stories from Powerfront","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.powerfront.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#webpage","url":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/","name":"Event Recap Archives - Powerfront Blog","isPartOf":{"@id":"https:\/\/www.powerfront.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.powerfront.com\/blog\/category\/event-recap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.powerfront.com\/blog\/category\/event-recap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.powerfront.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Event Recap"}]}]}},"_links":{"self":[{"href":"https:\/\/www.powerfront.com\/blog\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.powerfront.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.powerfront.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.powerfront.com\/blog\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}